{"id":7,"count":3,"description":"","link":"https:\/\/2alpes-snowboardschool.com\/en\/category\/guide\/","name":"Guide","slug":"guide","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/2alpes-snowboardschool.com\/en\/wp-json\/wp\/v2\/categories\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/2alpes-snowboardschool.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/2alpes-snowboardschool.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/2alpes-snowboardschool.com\/en\/wp-json\/wp\/v2\/posts?categories=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}